{"id":34622,"date":"2022-09-16T13:36:26","date_gmt":"2022-09-16T13:36:26","guid":{"rendered":"https:\/\/ap-hotelsresorts.com\/tertulia-f-and-b\/"},"modified":"2022-09-16T13:46:49","modified_gmt":"2022-09-16T13:46:49","slug":"tertulia-f-and-b","status":"publish","type":"post","link":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/","title":{"rendered":"Tertulia F&#038;B"},"content":{"rendered":"<p>El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&amp;B (Food and Beverage), en un almuerzo en AP Cabanas Beach &amp; Nature.<br \/>\nUna idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&amp;B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&amp;B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.<br \/>\nLos chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach &amp; Nature.<br \/>\nAgradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports &amp; Beach y del chef Tiago Cardoso AP Cabanas Beach &amp; Nature.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&amp;B (Food and Beverage), en un almuerzo en AP Cabanas Beach &amp; Nature. Una idea conjunta de la direcci\u00f3n general, los recursos [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":34616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[465],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tertulia F&amp;B - AP HOTELS &amp; RESORTS .<\/title>\n<meta name=\"description\" content=\"El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&amp;B (Food and Beverage), en un almuerzo en AP Cabanas Beach &amp; Nature.Una idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&amp;B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&amp;B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.Los chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach &amp; Nature.Agradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports &amp; Beach y del chef Tiago Cardoso AP Cabanas Beach &amp; Nature.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tertulia F&amp;B - AP HOTELS &amp; RESORTS .\" \/>\n<meta property=\"og:description\" content=\"El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&amp;B (Food and Beverage), en un almuerzo en AP Cabanas Beach &amp; Nature.Una idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&amp;B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&amp;B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.Los chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach &amp; Nature.Agradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports &amp; Beach y del chef Tiago Cardoso AP Cabanas Beach &amp; Nature.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/\" \/>\n<meta property=\"og:site_name\" content=\"AP HOTELS &amp; RESORTS .\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aphotelsresorts\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T13:36:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-16T13:46:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ApHotels\" \/>\n<meta name=\"twitter:site\" content=\"@ApHotels\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing ap\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/#organization\",\"name\":\"AP HOTELS & RESORTS\",\"url\":\"https:\/\/ap-hotelsresorts.com\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/aphotelsresorts\",\"https:\/\/www.instagram.com\/aphotelsresorts\/\",\"https:\/\/www.linkedin.com\/company\/ap-hotels-and-resorts\",\"https:\/\/www.youtube.com\/channel\/UCSmwGBz36kx2XALzeVAlKEg\",\"https:\/\/twitter.com\/ApHotels\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2021\/03\/logo-1.png\",\"contentUrl\":\"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2021\/03\/logo-1.png\",\"width\":\"3915\",\"height\":\"1388\",\"caption\":\"AP HOTELS & RESORTS\"},\"image\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/#website\",\"url\":\"https:\/\/ap-hotelsresorts.com\/\",\"name\":\"AP HOTELS &amp; RESORTS .\",\"description\":\"Albufeira . Faro . Portim\u00e3o . Tavira . Algarve\",\"publisher\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ap-hotelsresorts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg\",\"contentUrl\":\"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg\",\"width\":2560,\"height\":1659,\"caption\":\"Tertulia F & B\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#webpage\",\"url\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/\",\"name\":\"Tertulia F&B - AP HOTELS &amp; RESORTS .\",\"isPartOf\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#primaryimage\"},\"datePublished\":\"2022-09-16T13:36:26+00:00\",\"dateModified\":\"2022-09-16T13:46:49+00:00\",\"description\":\"El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&B (Food and Beverage), en un almuerzo en AP Cabanas Beach & Nature.Una idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.Los chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach & Nature.Agradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports & Beach y del chef Tiago Cardoso AP Cabanas Beach & Nature.\",\"breadcrumb\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ap-hotelsresorts.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tertulia F&#038;B\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#webpage\"},\"author\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/#\/schema\/person\/39ea63a33316ff09e0a075ae0a4bed49\"},\"headline\":\"Tertulia F&#038;B\",\"datePublished\":\"2022-09-16T13:36:26+00:00\",\"dateModified\":\"2022-09-16T13:46:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#webpage\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg\",\"articleSection\":[\"News (ES)\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/#\/schema\/person\/39ea63a33316ff09e0a075ae0a4bed49\",\"name\":\"marketing ap\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ap-hotelsresorts.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/80ea62fe6096f55fe36f17f2175dca2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/80ea62fe6096f55fe36f17f2175dca2f?s=96&d=mm&r=g\",\"caption\":\"marketing ap\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tertulia F&B - AP HOTELS &amp; RESORTS .","description":"El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&B (Food and Beverage), en un almuerzo en AP Cabanas Beach & Nature.Una idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.Los chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach & Nature.Agradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports & Beach y del chef Tiago Cardoso AP Cabanas Beach & Nature.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/","og_locale":"es_ES","og_type":"article","og_title":"Tertulia F&B - AP HOTELS &amp; RESORTS .","og_description":"El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&B (Food and Beverage), en un almuerzo en AP Cabanas Beach & Nature.Una idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.Los chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach & Nature.Agradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports & Beach y del chef Tiago Cardoso AP Cabanas Beach & Nature.","og_url":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/","og_site_name":"AP HOTELS &amp; RESORTS .","article_publisher":"https:\/\/www.facebook.com\/aphotelsresorts","article_published_time":"2022-09-16T13:36:26+00:00","article_modified_time":"2022-09-16T13:46:49+00:00","og_image":[{"width":2560,"height":1659,"url":"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@ApHotels","twitter_site":"@ApHotels","twitter_misc":{"Escrito por":"marketing ap","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/ap-hotelsresorts.com\/#organization","name":"AP HOTELS & RESORTS","url":"https:\/\/ap-hotelsresorts.com\/","sameAs":["https:\/\/www.facebook.com\/aphotelsresorts","https:\/\/www.instagram.com\/aphotelsresorts\/","https:\/\/www.linkedin.com\/company\/ap-hotels-and-resorts","https:\/\/www.youtube.com\/channel\/UCSmwGBz36kx2XALzeVAlKEg","https:\/\/twitter.com\/ApHotels"],"logo":{"@type":"ImageObject","@id":"https:\/\/ap-hotelsresorts.com\/#logo","inLanguage":"es","url":"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2021\/03\/logo-1.png","contentUrl":"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2021\/03\/logo-1.png","width":"3915","height":"1388","caption":"AP HOTELS & RESORTS"},"image":{"@id":"https:\/\/ap-hotelsresorts.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/ap-hotelsresorts.com\/#website","url":"https:\/\/ap-hotelsresorts.com\/","name":"AP HOTELS &amp; RESORTS .","description":"Albufeira . Faro . Portim\u00e3o . Tavira . Algarve","publisher":{"@id":"https:\/\/ap-hotelsresorts.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ap-hotelsresorts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#primaryimage","inLanguage":"es","url":"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg","contentUrl":"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg","width":2560,"height":1659,"caption":"Tertulia F & B"},{"@type":"WebPage","@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#webpage","url":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/","name":"Tertulia F&B - AP HOTELS &amp; RESORTS .","isPartOf":{"@id":"https:\/\/ap-hotelsresorts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#primaryimage"},"datePublished":"2022-09-16T13:36:26+00:00","dateModified":"2022-09-16T13:46:49+00:00","description":"El 15 de septiembre, los chefs de los hoteles de nuestro grupo se reunieron en una tertulia sobre F&B (Food and Beverage), en un almuerzo en AP Cabanas Beach & Nature.Una idea conjunta de la direcci\u00f3n general, los recursos humanos y la direcci\u00f3n de F&B, que permiti\u00f3 a los chefs de cada hotel intercambiar experiencias e ideas. Tambi\u00e9n se trataron temas como el proyecto de estandarizaci\u00f3n de los procedimientos de F&B, creando as\u00ed v\u00ednculos y reforzando el esp\u00edritu de equipo del departamento del grupo.Los chefs tambi\u00e9n tuvieron la oportunidad de conocer la unidad hotelera m\u00e1s reciente del grupo, el AP Cabanas Beach & Nature.Agradecemos la presencia del chef F\u00e1bio Horta, de AP Adriana Beach Resort, de AP Eva Senses, del chef Nelson Gomes, de AP Maria Nova Lounge, del chef Lu\u00eds Santos, del chef Jorge Santana de AP Victoria Sports & Beach y del chef Tiago Cardoso AP Cabanas Beach & Nature.","breadcrumb":{"@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ap-hotelsresorts.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tertulia F&#038;B"}]},{"@type":"Article","@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#article","isPartOf":{"@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#webpage"},"author":{"@id":"https:\/\/ap-hotelsresorts.com\/#\/schema\/person\/39ea63a33316ff09e0a075ae0a4bed49"},"headline":"Tertulia F&#038;B","datePublished":"2022-09-16T13:36:26+00:00","dateModified":"2022-09-16T13:46:49+00:00","mainEntityOfPage":{"@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#webpage"},"wordCount":173,"publisher":{"@id":"https:\/\/ap-hotelsresorts.com\/#organization"},"image":{"@id":"https:\/\/ap-hotelsresorts.com\/es\/tertulia-f-and-b\/#primaryimage"},"thumbnailUrl":"https:\/\/ap-hotelsresorts.com\/wp-content\/uploads\/2022\/09\/tertulia-web-scaled.jpg","articleSection":["News (ES)"],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ap-hotelsresorts.com\/#\/schema\/person\/39ea63a33316ff09e0a075ae0a4bed49","name":"marketing ap","image":{"@type":"ImageObject","@id":"https:\/\/ap-hotelsresorts.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/80ea62fe6096f55fe36f17f2175dca2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80ea62fe6096f55fe36f17f2175dca2f?s=96&d=mm&r=g","caption":"marketing ap"}}]}},"_links":{"self":[{"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/posts\/34622"}],"collection":[{"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/comments?post=34622"}],"version-history":[{"count":0,"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/posts\/34622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/media\/34616"}],"wp:attachment":[{"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/media?parent=34622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/categories?post=34622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ap-hotelsresorts.com\/es\/wp-json\/wp\/v2\/tags?post=34622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}